{"id":5929,"date":"2023-08-23T08:36:39","date_gmt":"2023-08-23T08:36:39","guid":{"rendered":"https:\/\/axiainvestments.com\/support-center\/"},"modified":"2025-12-23T23:30:27","modified_gmt":"2025-12-23T23:30:27","slug":"support-center","status":"publish","type":"page","link":"https:\/\/axiainvestments.com\/pt-br\/support-center\/","title":{"rendered":"Support Center"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5929\" class=\"elementor elementor-5929 elementor-2353\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2308faa elementor-section-full_width section_container elementor-section-height-default elementor-section-height-default\" data-id=\"2308faa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e4b6841\" data-id=\"e4b6841\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5868e6 elementor-widget elementor-widget-heading\" data-id=\"c5868e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 08-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Centro de apoio Axia<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-597816d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"597816d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 08-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Estamos sempre aqui a seu servi\u00e7o. Para sua conveni\u00eancia, pesquise na nossa base de dados para obter respostas r\u00e1pidas sobre qualquer assunto<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2df27d7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2df27d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6007724\" data-id=\"6007724\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e718738 elementor-widget elementor-widget-heading\" data-id=\"e718738\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Como fa\u00e7o para aprovisionar a minha conta?<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-884483e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"884483e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Disponibilizamos uma ampla variedade de formas de aprovisionar a sua conta, incluindo cart\u00e3o de cr\u00e9dito\/d\u00e9bito, transfer\u00eancia banc\u00e1ria e uma variedade de m\u00e9todos de pagamento online <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a5e19ae\" data-id=\"a5e19ae\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f74543 elementor-widget elementor-widget-heading\" data-id=\"9f74543\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">N\u00e3o consigo negociar, o que devo fazer?<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f20317 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7f20317\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Primeiro, consulte a nossa base de dados de perguntas comuns para detetar qual poder\u00e1 ser o problema. Se isso n\u00e3o ajudar, abra um ticket de apoio abaixo <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9759597\" data-id=\"9759597\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17dcff2 elementor-widget elementor-widget-heading\" data-id=\"17dcff2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Quantos pares de moedas posso negociar?<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3513d7e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3513d7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Pode negociar 50 pares de moedas na Axia, incluindo pares principais, cruzados e pares ex\u00f3ticos <\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4c93a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4c93a0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b55bc6\" data-id=\"6b55bc6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42e636a elementor-widget elementor-widget-heading\" data-id=\"42e636a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Perguntas Frequentes<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6956b3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6956b3b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ba6c6f\" data-id=\"9ba6c6f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f6b254 elementor-icon-list--layout-inline elementor-align-center elementor-widget__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5f6b254\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/axiabroker.com\/wp-content\/uploads\/prod-axia-main\/elementor\/css\/custom-widget-icon-list.min.css?ver=1787870175\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"accordion-tab active\" data-accordion=\"about\">Sobre Axia<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"accordion-tab\" data-accordion=\"general\">Quest\u00f5es gerais<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"accordion-tab\" data-accordion=\"mt5\">MT5 Plataforma<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0069f6 elementor-align-center elementor-widget__width-initial elementor-hidden-desktop elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f0069f6\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"accordion-tab active\" data-accordion=\"about\">Sobre Axia<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"accordion-tab\" data-accordion=\"general\">Quest\u00f5es gerais<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><span class=\"accordion-tab\" data-accordion=\"mt5\">MT5 Plataforma<\/span><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2b439d accordion-content active elementor-widget elementor-widget-accordion\" data-id=\"b2b439d\" data-element_type=\"widget\" data-accordion=\"about\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-accordion{text-align:start}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1871\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1871\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Axia \u00e9 regulamentada?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1871\"><p>Absolutamente. Axia \u00e9 orgulhosamente regulamentada pela FSA, Seychelles, SD034<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1872\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1872\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quais plataformas a Axia oferece?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1872\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1872\"><p>Voc\u00ea pode acessar sua conta e negociar no MetaTrader 4, MetaTrader 5, WebTrader e Mobile.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1873\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1873\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quais ativos posso negociar com a Axia?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1873\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1873\"><p>Temos uma variedade impressionante de ativos comerciais que s\u00e3o atualizados regularmente. Moedas, commodities, \u00edndices, a\u00e7\u00f5es e CFDs de criptomoedas podem ser negociados com a Axia.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1874\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1874\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quantos pares de moedas posso negociar?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1874\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1874\"><p>Voc\u00ea pode negociar 50 pares de moedas na Axia, incluindo pares principais, cruzados e pares ex\u00f3ticos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1875\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1875\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Axia \u00e9 adequada para iniciantes?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1875\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1875\"><p>Absolutamente. Oferecemos acesso \u00e0 nossa academia exclusiva que cobre o A-Z da negocia\u00e7\u00e3o, bem como a capacidade de aprender com especialistas e aprender com mais de 100 materiais educacionais. Totalmente personaliz\u00e1vel e com efic\u00e1cia comprovada, nossa academia \u00e9 ideal para iniciantes, traders avan\u00e7ados e profissionais.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1876\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1876\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Como come\u00e7o a negociar?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1876\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1876\"><p>Primeiro de tudo, voc\u00ea precisa abrir uma nova conta<a href=\"https:\/\/axiainvestments.com\/pt-br\/registration\/\"> <span style=\"text-decoration: underline; color: #000000;\">aqui<\/span><\/a>. Depois de se registrar, voc\u00ea precisar\u00e1 fornecer alguns documentos de verifica\u00e7\u00e3o que incluem comprovante de identidade (RG), comprovante de endere\u00e7o (uma conta de servi\u00e7o p\u00fablico recente) e comprovante de pagamento. Assim que seus documentos forem verificados, voc\u00ea poder\u00e1 depositar fundos em sua conta e come\u00e7ar a negociar.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1877\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1877\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Por que preciso fornecer meus documentos ao abrir uma conta?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1877\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1877\"><p>Com base na pr\u00e1tica comum, todas as empresas financeiras respeit\u00e1veis exigir\u00e3o estes documentos. Eles s\u00e3o necess\u00e1rios para proteger nossos clientes contra fraudes, ao mesmo tempo em que cumprem as regras e regulamentos antilavagem de dinheiro (AML) e antiterrorismo. Na Axia, mantemos os mais altos padr\u00f5es globais para proteger nossos clientes e cumprir todos os procedimentos globais de KYC.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1878\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1878\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O que significa comprovante de pagamento? Por que voc\u00ea precisa disso?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1878\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1878\"><p>Se voc\u00ea usar um cart\u00e3o de cr\u00e9dito para depositar em sua conta, precisaremos ter certeza de que voc\u00ea \u00e9 o propriet\u00e1rio do cart\u00e3o. Para o efeito necessitaremos de uma c\u00f3pia do seu cart\u00e3o de cr\u00e9dito, frente e verso, com os primeiros 12 d\u00edgitos ocultos, bem como o CVV. Tudo o que precisamos \u00e9 ver seu nome completo, os \u00faltimos 4 d\u00edgitos do cart\u00e3o e a data de validade. Se voc\u00ea usar uma transfer\u00eancia banc\u00e1ria ou m\u00e9todo on-line, precisaremos ver uma confirma\u00e7\u00e3o da transa\u00e7\u00e3o com seu nome, data e valor transferido.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1879\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1879\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Como fa\u00e7o para financiar minha conta?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1879\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1879\"><p>Oferecemos uma ampla variedade de maneiras de depositar em sua conta, incluindo cart\u00e3o de cr\u00e9dito\/d\u00e9bito, transfer\u00eancia eletr\u00f4nica e uma variedade de m\u00e9todos de pagamento on-line. Depois de registrar sua conta, voc\u00ea poder\u00e1 ver todos os m\u00e9todos dispon\u00edveis, com base na sua regi\u00e3o. Para qualquer d\u00favida sobre financiamento, sinta-se \u00e0 vontade para entrar em contato com nossa equipe de suporte.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18710\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-18710\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Tentei financiar minha conta com cart\u00e3o de cr\u00e9dito e n\u00e3o funcionou. Qual poderia ser o problema?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18710\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-18710\"><p>Ao entrar em contato com nossa equipe de suporte, poderemos ajud\u00e1-lo a obter uma compreens\u00e3o b\u00e1sica do motivo pelo qual a transa\u00e7\u00e3o n\u00e3o foi realizada e descartar erros de digita\u00e7\u00e3o ou datas de cart\u00e3o de cr\u00e9dito expiradas. \u00c0s vezes, voc\u00ea precisar\u00e1 entrar em contato com seu banco depois de falar conosco devido a fundos insuficientes na conta ou devido a limites de cart\u00e3o de cr\u00e9dito. Ocasionalmente, seu banco pode bloquear tentativas irregulares de dep\u00f3sito como uma camada adicional de seguran\u00e7a. Ao cham\u00e1-los voc\u00ea tamb\u00e9m pode autorizar a transa\u00e7\u00e3o e remover quaisquer bloqueios.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18711\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-18711\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Fiz uma transfer\u00eancia\/transa\u00e7\u00e3o com sucesso. Quando verei os fundos em minha conta?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18711\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-18711\"><p>Se voc\u00ea usou um cart\u00e3o de cr\u00e9dito ou uma solu\u00e7\u00e3o de carteira eletr\u00f4nica, dever\u00e1 ver os fundos em sua conta imediatamente. Se voc\u00ea fez uma transfer\u00eancia banc\u00e1ria, pode levar de 3 a 5 dias \u00fateis para que os fundos cheguem \u00e0 sua conta de negocia\u00e7\u00e3o. Para obter mais assist\u00eancia neste assunto, voc\u00ea pode sempre abrir um ticket de suporte e nossa equipe ir\u00e1 atend\u00ea-lo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18712\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-18712\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Posso usar mais de um cart\u00e3o para financiar minha conta?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18712\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-18712\"><p>Sim, desde que todos os cart\u00f5es utilizados estejam em seu nome. Precisaremos do comprovante de pagamento de cada cart\u00e3o separadamente. Observe que quando voc\u00ea faz saques, os fundos devem voltar para o mesmo cart\u00e3o a partir do qual foram originalmente depositados.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18713\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-18713\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Posso abrir uma conta conjunta com outra pessoa?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18713\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-18713\"><p>Sim. Precisaremos dos mesmos documentos de verifica\u00e7\u00e3o do segundo titular da conta, e a conta de negocia\u00e7\u00e3o deve estar em ambos os nomes. Neste caso, voc\u00ea poder\u00e1 utilizar seus pr\u00f3prios m\u00e9todos de pagamento em seus respectivos nomes, na mesma conta.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18714\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-18714\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">N\u00e3o consigo negociar, o que devo fazer?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18714\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-18714\"><p>Primeiro, verifique nosso banco de dados de consultas comuns para detectar qual poderia ser o problema. Se isso n\u00e3o ajudar, abra um ticket de suporte e nossa equipe ir\u00e1 ajud\u00e1-lo.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18715\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-18715\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Posso alterar a alavancagem da minha conta?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18715\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-18715\"><p>Depende do tipo de conta que voc\u00ea possui! Quanto mais alto voc\u00ea atualizar sua conta, maior ser\u00e1 a alavancagem. Axia oferece alavancagem de at\u00e9 1:400.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18716\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-18716\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Como fa\u00e7o para sacar fundos?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18716\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-18716\"><p>Retirar da sua conta \u00e9 simples. Quando estiver conectado \u00e0 sua conta, voc\u00ea pode clicar em \u201cRetirada\u201d, seguir os passos e come\u00e7aremos a processar sua solicita\u00e7\u00e3o assim que for enviada.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18717\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-18717\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quanto tempo leva para processar as retiradas?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18717\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-18717\"><p>Assim que o saque for processado, voc\u00ea receber\u00e1 uma notifica\u00e7\u00e3o do departamento banc\u00e1rio da Axia e ver\u00e1 o valor em quest\u00e3o deduzido de sua conta. A partir desse ponto, e ap\u00f3s a conclus\u00e3o dos requisitos de conformidade, os saques levam no m\u00ednimo 3 a 5 dias \u00fateis. Para transfer\u00eancias eletr\u00f4nicas, reserve um tempo extra, que est\u00e1 sujeito ao seu banco local, v\u00e1rios procedimentos em seu pa\u00eds, feriados nacionais e outros fatores.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Axia \\u00e9 regulamentada?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Absolutamente. Axia \\u00e9 orgulhosamente regulamentada pela FSA, Seychelles, SD034<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quais plataformas a Axia oferece?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Voc\\u00ea pode acessar sua conta e negociar no MetaTrader 4, MetaTrader 5, WebTrader e Mobile.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quais ativos posso negociar com a Axia?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Temos uma variedade impressionante de ativos comerciais que s\\u00e3o atualizados regularmente. Moedas, commodities, \\u00edndices, a\\u00e7\\u00f5es e CFDs de criptomoedas podem ser negociados com a Axia.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quantos pares de moedas posso negociar?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Voc\\u00ea pode negociar 50 pares de moedas na Axia, incluindo pares principais, cruzados e pares ex\\u00f3ticos.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Axia \\u00e9 adequada para iniciantes?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Absolutamente. Oferecemos acesso \\u00e0 nossa academia exclusiva que cobre o A-Z da negocia\\u00e7\\u00e3o, bem como a capacidade de aprender com especialistas e aprender com mais de 100 materiais educacionais. Totalmente personaliz\\u00e1vel e com efic\\u00e1cia comprovada, nossa academia \\u00e9 ideal para iniciantes, traders avan\\u00e7ados e profissionais.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Como come\\u00e7o a negociar?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Primeiro de tudo, voc\\u00ea precisa abrir uma nova conta<a href=\\\"https:\\\/\\\/axiainvestments.com\\\/pt-br\\\/registration\\\/\\\"> <span style=\\\"text-decoration: underline; color: #000000;\\\">aqui<\\\/span><\\\/a>. Depois de se registrar, voc\\u00ea precisar\\u00e1 fornecer alguns documentos de verifica\\u00e7\\u00e3o que incluem comprovante de identidade (RG), comprovante de endere\\u00e7o (uma conta de servi\\u00e7o p\\u00fablico recente) e comprovante de pagamento. Assim que seus documentos forem verificados, voc\\u00ea poder\\u00e1 depositar fundos em sua conta e come\\u00e7ar a negociar.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Por que preciso fornecer meus documentos ao abrir uma conta?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Com base na pr\\u00e1tica comum, todas as empresas financeiras respeit\\u00e1veis exigir\\u00e3o estes documentos. Eles s\\u00e3o necess\\u00e1rios para proteger nossos clientes contra fraudes, ao mesmo tempo em que cumprem as regras e regulamentos antilavagem de dinheiro (AML) e antiterrorismo. Na Axia, mantemos os mais altos padr\\u00f5es globais para proteger nossos clientes e cumprir todos os procedimentos globais de KYC.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"O que significa comprovante de pagamento? Por que voc\\u00ea precisa disso?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Se voc\\u00ea usar um cart\\u00e3o de cr\\u00e9dito para depositar em sua conta, precisaremos ter certeza de que voc\\u00ea \\u00e9 o propriet\\u00e1rio do cart\\u00e3o. Para o efeito necessitaremos de uma c\\u00f3pia do seu cart\\u00e3o de cr\\u00e9dito, frente e verso, com os primeiros 12 d\\u00edgitos ocultos, bem como o CVV. Tudo o que precisamos \\u00e9 ver seu nome completo, os \\u00faltimos 4 d\\u00edgitos do cart\\u00e3o e a data de validade. Se voc\\u00ea usar uma transfer\\u00eancia banc\\u00e1ria ou m\\u00e9todo on-line, precisaremos ver uma confirma\\u00e7\\u00e3o da transa\\u00e7\\u00e3o com seu nome, data e valor transferido.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Como fa\\u00e7o para financiar minha conta?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Oferecemos uma ampla variedade de maneiras de depositar em sua conta, incluindo cart\\u00e3o de cr\\u00e9dito\\\/d\\u00e9bito, transfer\\u00eancia eletr\\u00f4nica e uma variedade de m\\u00e9todos de pagamento on-line. Depois de registrar sua conta, voc\\u00ea poder\\u00e1 ver todos os m\\u00e9todos dispon\\u00edveis, com base na sua regi\\u00e3o. Para qualquer d\\u00favida sobre financiamento, sinta-se \\u00e0 vontade para entrar em contato com nossa equipe de suporte.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Tentei financiar minha conta com cart\\u00e3o de cr\\u00e9dito e n\\u00e3o funcionou. Qual poderia ser o problema?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Ao entrar em contato com nossa equipe de suporte, poderemos ajud\\u00e1-lo a obter uma compreens\\u00e3o b\\u00e1sica do motivo pelo qual a transa\\u00e7\\u00e3o n\\u00e3o foi realizada e descartar erros de digita\\u00e7\\u00e3o ou datas de cart\\u00e3o de cr\\u00e9dito expiradas. \\u00c0s vezes, voc\\u00ea precisar\\u00e1 entrar em contato com seu banco depois de falar conosco devido a fundos insuficientes na conta ou devido a limites de cart\\u00e3o de cr\\u00e9dito. Ocasionalmente, seu banco pode bloquear tentativas irregulares de dep\\u00f3sito como uma camada adicional de seguran\\u00e7a. Ao cham\\u00e1-los voc\\u00ea tamb\\u00e9m pode autorizar a transa\\u00e7\\u00e3o e remover quaisquer bloqueios.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Fiz uma transfer\\u00eancia\\\/transa\\u00e7\\u00e3o com sucesso. Quando verei os fundos em minha conta?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Se voc\\u00ea usou um cart\\u00e3o de cr\\u00e9dito ou uma solu\\u00e7\\u00e3o de carteira eletr\\u00f4nica, dever\\u00e1 ver os fundos em sua conta imediatamente. Se voc\\u00ea fez uma transfer\\u00eancia banc\\u00e1ria, pode levar de 3 a 5 dias \\u00fateis para que os fundos cheguem \\u00e0 sua conta de negocia\\u00e7\\u00e3o. Para obter mais assist\\u00eancia neste assunto, voc\\u00ea pode sempre abrir um ticket de suporte e nossa equipe ir\\u00e1 atend\\u00ea-lo.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Posso usar mais de um cart\\u00e3o para financiar minha conta?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Sim, desde que todos os cart\\u00f5es utilizados estejam em seu nome. Precisaremos do comprovante de pagamento de cada cart\\u00e3o separadamente. Observe que quando voc\\u00ea faz saques, os fundos devem voltar para o mesmo cart\\u00e3o a partir do qual foram originalmente depositados.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Posso abrir uma conta conjunta com outra pessoa?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Sim. Precisaremos dos mesmos documentos de verifica\\u00e7\\u00e3o do segundo titular da conta, e a conta de negocia\\u00e7\\u00e3o deve estar em ambos os nomes. Neste caso, voc\\u00ea poder\\u00e1 utilizar seus pr\\u00f3prios m\\u00e9todos de pagamento em seus respectivos nomes, na mesma conta.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"N\\u00e3o consigo negociar, o que devo fazer?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Primeiro, verifique nosso banco de dados de consultas comuns para detectar qual poderia ser o problema. Se isso n\\u00e3o ajudar, abra um ticket de suporte e nossa equipe ir\\u00e1 ajud\\u00e1-lo.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Posso alterar a alavancagem da minha conta?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Depende do tipo de conta que voc\\u00ea possui! Quanto mais alto voc\\u00ea atualizar sua conta, maior ser\\u00e1 a alavancagem. Axia oferece alavancagem de at\\u00e9 1:400.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Como fa\\u00e7o para sacar fundos?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Retirar da sua conta \\u00e9 simples. Quando estiver conectado \\u00e0 sua conta, voc\\u00ea pode clicar em \\u201cRetirada\\u201d, seguir os passos e come\\u00e7aremos a processar sua solicita\\u00e7\\u00e3o assim que for enviada.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quanto tempo leva para processar as retiradas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Assim que o saque for processado, voc\\u00ea receber\\u00e1 uma notifica\\u00e7\\u00e3o do departamento banc\\u00e1rio da Axia e ver\\u00e1 o valor em quest\\u00e3o deduzido de sua conta. A partir desse ponto, e ap\\u00f3s a conclus\\u00e3o dos requisitos de conformidade, os saques levam no m\\u00ednimo 3 a 5 dias \\u00fateis. Para transfer\\u00eancias eletr\\u00f4nicas, reserve um tempo extra, que est\\u00e1 sujeito ao seu banco local, v\\u00e1rios procedimentos em seu pa\\u00eds, feriados nacionais e outros fatores.<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad62b1e accordion-content elementor-widget elementor-widget-accordion\" data-id=\"ad62b1e\" data-element_type=\"widget\" data-accordion=\"general\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1811\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O que \u00e9 forex?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1811\"><p>Tamb\u00e9m conhecido como FX, Forex \u00e9 o mercado global de c\u00e2mbio ou c\u00e2mbio. \u00c9 o maior mercado financeiro do mundo em termos de volumes di\u00e1rios de negocia\u00e7\u00e3o, com uma m\u00e9dia de 6,6 bili\u00f5es de d\u00f3lares por dia, de acordo com os mais recentes especialistas do Banco de Compensa\u00e7\u00f5es Internacionais (BIS).<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1812\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1812\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Onde est\u00e1 localizado o mercado cambial?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1812\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1812\"><p>Forex \u00e9 um mercado descentralizado, onde as opera\u00e7\u00f5es comerciais n\u00e3o ocorrem em um s\u00f3 lugar, como uma bolsa de valores. No entanto, todas as opera\u00e7\u00f5es comerciais s\u00e3o lan\u00e7adas atrav\u00e9s da Internet atrav\u00e9s de uma rede complicada de diferentes bancos no mundo. Este processo \u00e9 conhecido como negocia\u00e7\u00e3o no mercado de balc\u00e3o (OTC).<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1813\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1813\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O que \u00e9 negocia\u00e7\u00e3o forex?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1813\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1813\"><p>C\u00e2mbio ou negocia\u00e7\u00e3o de moeda refere-se ao processo de troca de uma moeda por outra. \u00c9 uma opera\u00e7\u00e3o financeira comum que pode ser realizada para fins comerciais ou especulando sobre movimentos de pre\u00e7os e obten\u00e7\u00e3o de lucro \u2013 que representa o volume de negocia\u00e7\u00e3o.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1814\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1814\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quais s\u00e3o os hor\u00e1rios de negocia\u00e7\u00e3o no mercado cambial?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1814\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1814\"><p>O mercado cambial est\u00e1 dispon\u00edvel 24 horas, cinco dias por semana, de domingo \u00e0 noite at\u00e9 sexta-feira \u00e0 noite. Isto deve-se aos diferentes fusos hor\u00e1rios internacionais que lhe permitem negociar a qualquer hora do dia. Existem grandes sess\u00f5es de negocia\u00e7\u00e3o nestes tr\u00eas sites:<\/p><p>\u2022 T\u00f3quio (sess\u00e3o asi\u00e1tica)<\/p><p>\u2022 Londres (sess\u00e3o europeia)<\/p><p>\u2022 Nova York (sess\u00e3o norte-americana) <\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1815\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1815\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O que s\u00e3o pares de moedas?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1815\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1815\"><p>Primeiramente, a negocia\u00e7\u00e3o forex \u00e9 o processo de troca de uma moeda por outra. Assim, as moedas do mercado cambial s\u00e3o sempre negociadas em pares, onde, no par, \u00e9 mostrado o pre\u00e7o da moeda, que \u00e9 a moeda base, versus a outra, conhecida como moeda de cota\u00e7\u00e3o. Os pares de moedas usam siglas de moedas e nomes de na\u00e7\u00f5es que representam. O processo de compra ou venda do d\u00f3lar americano versus o euro \u00e9 negociado entre a moeda d\u00f3lar e seu s\u00edmbolo (USD) e a moeda euro e seu s\u00edmbolo (EUR). O par de moedas \u00e9 EUR\/USD. A cota\u00e7\u00e3o EUR\/USD permite saber quantos d\u00f3lares americanos (USD) voc\u00ea precisa trocar por um euro (EUR).<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1816\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1816\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O que \u00e9 uma taxa de c\u00e2mbio?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1816\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1816\"><p>A taxa de c\u00e2mbio representa o valor de uma moeda em rela\u00e7\u00e3o a outra. Em outras palavras, \u00e9 a taxa pela qual uma moeda \u00e9 trocada por outra. Por exemplo, vamos considerar o par EUR\/USD (EUR\/USD = 1,2500) como exemplo. Ent\u00e3o, o euro \u00e9 a moeda base e o d\u00f3lar \u00e9 a moeda de cota\u00e7\u00e3o. A partir de agora, 1 euro equivale a 1.2500 d\u00f3lares. A taxa de c\u00e2mbio representa o valor da moeda de cota\u00e7\u00e3o que deve ser pago para obter uma \u201cunidade\u201d da moeda base. Um aumento da taxa de c\u00e2mbio reflete o aumento da moeda base em rela\u00e7\u00e3o \u00e0 moeda de cota\u00e7\u00e3o. Da mesma forma, uma queda na taxa de c\u00e2mbio reflete a queda da moeda base em rela\u00e7\u00e3o \u00e0 moeda de cota\u00e7\u00e3o. Leia mais sobre pares de moedas aqui.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1817\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1817\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Como s\u00e3o determinadas as taxas de c\u00e2mbio no mercado cambial?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1817\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1817\"><p>Como qualquer outro mercado, a fixa\u00e7\u00e3o de pre\u00e7os depende do volume de oferta e procura de uma determinada moeda em compara\u00e7\u00e3o com outras moedas, que s\u00e3o afectadas por muitos factores econ\u00f3micos e pol\u00edticos chamados factores fundamentais. Al\u00e9m disso, existem tamb\u00e9m fatores t\u00e9cnicos que se baseiam no estudo e an\u00e1lise de movimentos hist\u00f3ricos de pre\u00e7os por meio de gr\u00e1ficos e indicadores t\u00e9cnicos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1818\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1818\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O que \u00e9 negocia\u00e7\u00e3o de CFD?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1818\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1818\"><p>Refere-se ao contrato por diferen\u00e7a. \u00c9 um instrumento financeiro que permite ao trader comprar e vender, especulando sobre diversos ativos financeiros sem possu\u00ed-los. \u00c9 um contrato comercial entre o trader (voc\u00ea) e a corretora ou banco baseado na \u201cdiferen\u00e7a\u201d de pre\u00e7os dos ativos financeiros. Ao negociar CFDs, voc\u00ea concorda em trocar a diferen\u00e7a no pre\u00e7o do ativo desde o momento em que o contrato \u00e9 aberto at\u00e9 o momento em que \u00e9 fechado. Um dos principais benef\u00edcios da negocia\u00e7\u00e3o de CFDs \u00e9 que voc\u00ea pode especular sobre os movimentos de pre\u00e7os em qualquer dire\u00e7\u00e3o, onde o lucro ou a perda depende da precis\u00e3o das suas antecipa\u00e7\u00f5es.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1819\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1819\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quais s\u00e3o as vantagens da negocia\u00e7\u00e3o de CFDs?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1819\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1819\"><p>Existem muitas vantagens que contribu\u00edram efetivamente para a difus\u00e3o da negocia\u00e7\u00e3o de CFD. Uma delas \u00e9 a negocia\u00e7\u00e3o com alavancagem, que permite abrir neg\u00f3cios muito maiores que o capital da conta de negocia\u00e7\u00e3o. Tamb\u00e9m d\u00e1 a oportunidade de obter lucros, seja no mercado em queda ou emergente no mercado de a\u00e7\u00f5es, por exemplo. Al\u00e9m disso, os CFDs permitem ao comprador negociar um grande n\u00famero de ativos financeiros a custos m\u00ednimos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18110\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-18110\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">A negocia\u00e7\u00e3o forex \u00e9 arriscada?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18110\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-18110\"><p>Qualquer investimento de qualquer tipo envolve um certo risco, mas existem investimentos de alto e baixo risco. Ali\u00e1s, o risco do investimento tem relatividade direta com os retornos esperados. A negocia\u00e7\u00e3o Forex pertence \u00e0 categoria de investimento de alto risco. Em troca, oferece grandes oportunidades de obten\u00e7\u00e3o de lucros. O segredo deste sucesso reside numa rigorosa estrat\u00e9gia de gest\u00e3o de risco. Axia Trade oferece um conjunto completo de ferramentas de negocia\u00e7\u00e3o que permitem ao comprador oferecer o maior grau de prote\u00e7\u00e3o e profissionalismo no gerenciamento de transa\u00e7\u00f5es.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18111\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-18111\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Como posso come\u00e7ar a negociar?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-18111\"><p>Tudo o que voc\u00ea precisa fazer \u00e9 abrir uma conta de negocia\u00e7\u00e3o na Axia para acessar diversos mercados financeiros atrav\u00e9s das seguintes etapas:<\/p><p>\u2022 Preencha o formul\u00e1rio de informa\u00e7\u00f5es pessoais e registre uma nova conta aqui.<\/p><p>\u2022 Voc\u00ea receber\u00e1 uma mensagem para confirmar o endere\u00e7o de e-mail.<\/p><p>\u2022 Fa\u00e7a login na plataforma Axia WebTrader diretamente no site da Axia clicando no \u00edcone \u201cLogin\u201d no canto superior direito da p\u00e1gina.<\/p><p>\u2022 Atrav\u00e9s do centro de gerenciamento de contas no canto superior esquerdo, voc\u00ea pode concluir o procedimento de verifica\u00e7\u00e3o de conta e depositar fundos para come\u00e7ar a negociar imediatamente.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18112\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-18112\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qual \u00e9 a quantia certa para come\u00e7ar a negociar forex?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18112\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-18112\"><p>N\u00e3o existe uma resposta \u00fanica para esta quest\u00e3o porque a determina\u00e7\u00e3o deste montante depende de muitas vari\u00e1veis que diferem de um trader para outro. O mais importante deles s\u00e3o seus objetivos comerciais e a quantidade de capital que voc\u00ea pode perder sem afetar sua situa\u00e7\u00e3o financeira. Al\u00e9m disso, a estrat\u00e9gia de negocia\u00e7\u00e3o e o gerenciamento de risco aplicados e, por fim, as condi\u00e7\u00f5es de negocia\u00e7\u00e3o fornecidas pela corretora com a qual voc\u00ea trabalha.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-18113\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-18113\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Posso come\u00e7ar a negociar forex com apenas $100?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-18113\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-18113\"><p>Sim, \u00e9 poss\u00edvel come\u00e7ar a negociar forex com $100. Entretanto, este montante baixo limitar\u00e1 bastante as suas op\u00e7\u00f5es de negocia\u00e7\u00e3o e potencial de lucro. Digamos que voc\u00ea conseguiu um lucro de 10%, isso significa que voc\u00ea ganhou $10. Por outro lado, se sua conta tiver US$ 10.000, seu lucro ser\u00e1 de US$ 1.000. A Axia oferece muitos tipos de contas de negocia\u00e7\u00e3o, come\u00e7ando com um m\u00ednimo de US$ 500 para a conta Bronze, enquanto a conta Gold permite que voc\u00ea comece com um dep\u00f3sito m\u00ednimo de US$ 10.000, que \u00e9 a conta mais popular entre os traders.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"O que \\u00e9 forex?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Tamb\\u00e9m conhecido como FX, Forex \\u00e9 o mercado global de c\\u00e2mbio ou c\\u00e2mbio. \\u00c9 o maior mercado financeiro do mundo em termos de volumes di\\u00e1rios de negocia\\u00e7\\u00e3o, com uma m\\u00e9dia de 6,6 bili\\u00f5es de d\\u00f3lares por dia, de acordo com os mais recentes especialistas do Banco de Compensa\\u00e7\\u00f5es Internacionais (BIS).<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Onde est\\u00e1 localizado o mercado cambial?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Forex \\u00e9 um mercado descentralizado, onde as opera\\u00e7\\u00f5es comerciais n\\u00e3o ocorrem em um s\\u00f3 lugar, como uma bolsa de valores. No entanto, todas as opera\\u00e7\\u00f5es comerciais s\\u00e3o lan\\u00e7adas atrav\\u00e9s da Internet atrav\\u00e9s de uma rede complicada de diferentes bancos no mundo. Este processo \\u00e9 conhecido como negocia\\u00e7\\u00e3o no mercado de balc\\u00e3o (OTC).<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"O que \\u00e9 negocia\\u00e7\\u00e3o forex?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>C\\u00e2mbio ou negocia\\u00e7\\u00e3o de moeda refere-se ao processo de troca de uma moeda por outra. \\u00c9 uma opera\\u00e7\\u00e3o financeira comum que pode ser realizada para fins comerciais ou especulando sobre movimentos de pre\\u00e7os e obten\\u00e7\\u00e3o de lucro \\u2013 que representa o volume de negocia\\u00e7\\u00e3o.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quais s\\u00e3o os hor\\u00e1rios de negocia\\u00e7\\u00e3o no mercado cambial?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>O mercado cambial est\\u00e1 dispon\\u00edvel 24 horas, cinco dias por semana, de domingo \\u00e0 noite at\\u00e9 sexta-feira \\u00e0 noite. Isto deve-se aos diferentes fusos hor\\u00e1rios internacionais que lhe permitem negociar a qualquer hora do dia. Existem grandes sess\\u00f5es de negocia\\u00e7\\u00e3o nestes tr\\u00eas sites:<\\\/p><p>\\u2022 T\\u00f3quio (sess\\u00e3o asi\\u00e1tica)<\\\/p><p>\\u2022 Londres (sess\\u00e3o europeia)<\\\/p><p>\\u2022 Nova York (sess\\u00e3o norte-americana) <\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"O que s\\u00e3o pares de moedas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Primeiramente, a negocia\\u00e7\\u00e3o forex \\u00e9 o processo de troca de uma moeda por outra. Assim, as moedas do mercado cambial s\\u00e3o sempre negociadas em pares, onde, no par, \\u00e9 mostrado o pre\\u00e7o da moeda, que \\u00e9 a moeda base, versus a outra, conhecida como moeda de cota\\u00e7\\u00e3o. Os pares de moedas usam siglas de moedas e nomes de na\\u00e7\\u00f5es que representam. O processo de compra ou venda do d\\u00f3lar americano versus o euro \\u00e9 negociado entre a moeda d\\u00f3lar e seu s\\u00edmbolo (USD) e a moeda euro e seu s\\u00edmbolo (EUR). O par de moedas \\u00e9 EUR\\\/USD. A cota\\u00e7\\u00e3o EUR\\\/USD permite saber quantos d\\u00f3lares americanos (USD) voc\\u00ea precisa trocar por um euro (EUR).<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"O que \\u00e9 uma taxa de c\\u00e2mbio?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>A taxa de c\\u00e2mbio representa o valor de uma moeda em rela\\u00e7\\u00e3o a outra. Em outras palavras, \\u00e9 a taxa pela qual uma moeda \\u00e9 trocada por outra. Por exemplo, vamos considerar o par EUR\\\/USD (EUR\\\/USD = 1,2500) como exemplo. Ent\\u00e3o, o euro \\u00e9 a moeda base e o d\\u00f3lar \\u00e9 a moeda de cota\\u00e7\\u00e3o. A partir de agora, 1 euro equivale a 1.2500 d\\u00f3lares. A taxa de c\\u00e2mbio representa o valor da moeda de cota\\u00e7\\u00e3o que deve ser pago para obter uma \\u201cunidade\\u201d da moeda base. Um aumento da taxa de c\\u00e2mbio reflete o aumento da moeda base em rela\\u00e7\\u00e3o \\u00e0 moeda de cota\\u00e7\\u00e3o. Da mesma forma, uma queda na taxa de c\\u00e2mbio reflete a queda da moeda base em rela\\u00e7\\u00e3o \\u00e0 moeda de cota\\u00e7\\u00e3o. Leia mais sobre pares de moedas aqui.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Como s\\u00e3o determinadas as taxas de c\\u00e2mbio no mercado cambial?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Como qualquer outro mercado, a fixa\\u00e7\\u00e3o de pre\\u00e7os depende do volume de oferta e procura de uma determinada moeda em compara\\u00e7\\u00e3o com outras moedas, que s\\u00e3o afectadas por muitos factores econ\\u00f3micos e pol\\u00edticos chamados factores fundamentais. Al\\u00e9m disso, existem tamb\\u00e9m fatores t\\u00e9cnicos que se baseiam no estudo e an\\u00e1lise de movimentos hist\\u00f3ricos de pre\\u00e7os por meio de gr\\u00e1ficos e indicadores t\\u00e9cnicos.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"O que \\u00e9 negocia\\u00e7\\u00e3o de CFD?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Refere-se ao contrato por diferen\\u00e7a. \\u00c9 um instrumento financeiro que permite ao trader comprar e vender, especulando sobre diversos ativos financeiros sem possu\\u00ed-los. \\u00c9 um contrato comercial entre o trader (voc\\u00ea) e a corretora ou banco baseado na \\u201cdiferen\\u00e7a\\u201d de pre\\u00e7os dos ativos financeiros. Ao negociar CFDs, voc\\u00ea concorda em trocar a diferen\\u00e7a no pre\\u00e7o do ativo desde o momento em que o contrato \\u00e9 aberto at\\u00e9 o momento em que \\u00e9 fechado. Um dos principais benef\\u00edcios da negocia\\u00e7\\u00e3o de CFDs \\u00e9 que voc\\u00ea pode especular sobre os movimentos de pre\\u00e7os em qualquer dire\\u00e7\\u00e3o, onde o lucro ou a perda depende da precis\\u00e3o das suas antecipa\\u00e7\\u00f5es.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quais s\\u00e3o as vantagens da negocia\\u00e7\\u00e3o de CFDs?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Existem muitas vantagens que contribu\\u00edram efetivamente para a difus\\u00e3o da negocia\\u00e7\\u00e3o de CFD. Uma delas \\u00e9 a negocia\\u00e7\\u00e3o com alavancagem, que permite abrir neg\\u00f3cios muito maiores que o capital da conta de negocia\\u00e7\\u00e3o. Tamb\\u00e9m d\\u00e1 a oportunidade de obter lucros, seja no mercado em queda ou emergente no mercado de a\\u00e7\\u00f5es, por exemplo. Al\\u00e9m disso, os CFDs permitem ao comprador negociar um grande n\\u00famero de ativos financeiros a custos m\\u00ednimos.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"A negocia\\u00e7\\u00e3o forex \\u00e9 arriscada?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Qualquer investimento de qualquer tipo envolve um certo risco, mas existem investimentos de alto e baixo risco. Ali\\u00e1s, o risco do investimento tem relatividade direta com os retornos esperados. A negocia\\u00e7\\u00e3o Forex pertence \\u00e0 categoria de investimento de alto risco. Em troca, oferece grandes oportunidades de obten\\u00e7\\u00e3o de lucros. O segredo deste sucesso reside numa rigorosa estrat\\u00e9gia de gest\\u00e3o de risco. Axia Trade oferece um conjunto completo de ferramentas de negocia\\u00e7\\u00e3o que permitem ao comprador oferecer o maior grau de prote\\u00e7\\u00e3o e profissionalismo no gerenciamento de transa\\u00e7\\u00f5es.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Como posso come\\u00e7ar a negociar?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Tudo o que voc\\u00ea precisa fazer \\u00e9 abrir uma conta de negocia\\u00e7\\u00e3o na Axia para acessar diversos mercados financeiros atrav\\u00e9s das seguintes etapas:<\\\/p><p>\\u2022 Preencha o formul\\u00e1rio de informa\\u00e7\\u00f5es pessoais e registre uma nova conta aqui.<\\\/p><p>\\u2022 Voc\\u00ea receber\\u00e1 uma mensagem para confirmar o endere\\u00e7o de e-mail.<\\\/p><p>\\u2022 Fa\\u00e7a login na plataforma Axia WebTrader diretamente no site da Axia clicando no \\u00edcone \\u201cLogin\\u201d no canto superior direito da p\\u00e1gina.<\\\/p><p>\\u2022 Atrav\\u00e9s do centro de gerenciamento de contas no canto superior esquerdo, voc\\u00ea pode concluir o procedimento de verifica\\u00e7\\u00e3o de conta e depositar fundos para come\\u00e7ar a negociar imediatamente.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Qual \\u00e9 a quantia certa para come\\u00e7ar a negociar forex?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>N\\u00e3o existe uma resposta \\u00fanica para esta quest\\u00e3o porque a determina\\u00e7\\u00e3o deste montante depende de muitas vari\\u00e1veis que diferem de um trader para outro. O mais importante deles s\\u00e3o seus objetivos comerciais e a quantidade de capital que voc\\u00ea pode perder sem afetar sua situa\\u00e7\\u00e3o financeira. Al\\u00e9m disso, a estrat\\u00e9gia de negocia\\u00e7\\u00e3o e o gerenciamento de risco aplicados e, por fim, as condi\\u00e7\\u00f5es de negocia\\u00e7\\u00e3o fornecidas pela corretora com a qual voc\\u00ea trabalha.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Posso come\\u00e7ar a negociar forex com apenas $100?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Sim, \\u00e9 poss\\u00edvel come\\u00e7ar a negociar forex com $100. Entretanto, este montante baixo limitar\\u00e1 bastante as suas op\\u00e7\\u00f5es de negocia\\u00e7\\u00e3o e potencial de lucro. Digamos que voc\\u00ea conseguiu um lucro de 10%, isso significa que voc\\u00ea ganhou $10. Por outro lado, se sua conta tiver US$ 10.000, seu lucro ser\\u00e1 de US$ 1.000. A Axia oferece muitos tipos de contas de negocia\\u00e7\\u00e3o, come\\u00e7ando com um m\\u00ednimo de US$ 500 para a conta Bronze, enquanto a conta Gold permite que voc\\u00ea comece com um dep\\u00f3sito m\\u00ednimo de US$ 10.000, que \\u00e9 a conta mais popular entre os traders.<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98dc1e6 accordion-content elementor-widget elementor-widget-accordion\" data-id=\"98dc1e6\" data-element_type=\"widget\" data-accordion=\"mt5\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1601\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1601\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O que \u00e9 a plataforma MetaTrader 5 (MT5)?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1601\"><p>MetaTrader 5 ou MT5 \u00e9 uma plataforma de negocia\u00e7\u00e3o de m\u00faltiplos ativos que permite negocia\u00e7\u00e3o de Forex, a\u00e7\u00f5es e futuros. Ele fornece ferramentas exemplares para an\u00e1lise t\u00e9cnica abrangente de movimentos de pre\u00e7os, uso de negocia\u00e7\u00e3o automatizada usando algoritmos de software (bots de negocia\u00e7\u00e3o, consultores especializados) e servi\u00e7os de negocia\u00e7\u00e3o de c\u00f3pias.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1602\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1602\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Por que devo usar o MT5? \u00c9 diferente da plataforma MetaTrader 4 (MT4)?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1602\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1602\"><p>A plataforma MetaTrader 5 foi lan\u00e7ada em 2010, cinco anos ap\u00f3s o lan\u00e7amento do MetaTrader 4, que era, na altura, a plataforma mais utilizada entre traders novatos e corretoras para negocia\u00e7\u00e3o no mercado Forex atrav\u00e9s de CFDs. A plataforma MetaTrader 5 conseguiu manter a caracter\u00edstica mais importante, que \u00e9 a facilidade de uso, al\u00e9m de configurar um conjunto de recursos principais adicionais, especialmente gr\u00e1ficos. Alguns dos recursos do MT5 incluem:<br \/>\u2013 21 prazos localizados nos gr\u00e1ficos em compara\u00e7\u00e3o com 9 prazos para MT4.<br \/>\u2013 8 indicadores t\u00e9cnicos adicionais.<br \/>\u2013 Uso de MQL5 para programa\u00e7\u00e3o de negocia\u00e7\u00e3o automatizada (negocia\u00e7\u00e3o algor\u00edtmica), que fornece mais ferramentas e execu\u00e7\u00e3o 20 vezes mais r\u00e1pida que MQL4 para a plataforma MetaTrader 4.<br \/>\u2013 Mais ordens de negocia\u00e7\u00e3o.<br \/>\u2013 Negoceie um n\u00famero infinitamente maior de ativos financeiros, enquanto a plataforma MT4 \u00e9 projetada especificamente para negociar CFDs para um n\u00famero limitado de pares forex.<br \/>\u2013 Possibilidade de negocia\u00e7\u00e3o de a\u00e7\u00f5es reais em diversas bolsas de valores<br \/>\u2013 Abertura de neg\u00f3cios de hedge<br \/>\u2013 Calend\u00e1rio econ\u00f4mico<br \/>Leia mais: Por que a plataforma de negocia\u00e7\u00e3o MetaTrader 5 \u00e9 a melhor.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1603\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1603\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Como posso baixar e instalar a plataforma MT5?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1603\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1603\"><p>Voc\u00ea pode baixar e instalar a plataforma MetaTrader 5 do site Axia Trade aqui. Depois de instalar a plataforma, voc\u00ea pode abrir uma conta de negocia\u00e7\u00e3o demo ou usar os dados de uma conta real para entrar na plataforma e come\u00e7ar a negociar.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1604\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1604\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O MT5 \u00e9 adequado para iniciantes?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1604\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1604\"><p>Sim, uma das caracter\u00edsticas mais importantes da plataforma MetaTrader 5 \u00e9 a extrema simplicidade da interface do usu\u00e1rio. Permite a qualquer trader, independentemente da sua experi\u00eancia no mercado, utiliz\u00e1-lo quase diretamente, sem necessidade de especificar tempo e esfor\u00e7o para aprender e habituar-se a ele. Tamb\u00e9m possui um servi\u00e7o de copy trades, que permite que traders novatos sigam e copiem traders profissionais de sucesso. A conhecida plataforma MetaTrader possui uma grande base de usu\u00e1rios ativos e forma uma comunidade forte que fornece muitas respostas e solu\u00e7\u00f5es para todos os tipos de problemas que um trader iniciante pode encontrar.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1605\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1605\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quais ativos financeiros est\u00e3o dispon\u00edveis para negocia\u00e7\u00e3o na plataforma MT5?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1605\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1605\"><p>Depende da corretora com a qual voc\u00ea est\u00e1 negociando, do tipo de ativos e dos mercados financeiros nos quais voc\u00ea presta servi\u00e7os de negocia\u00e7\u00e3o. Voc\u00ea pode negociar todos os CFDs de pares de moedas (Forex), a\u00e7\u00f5es globais e \u00e1rabes, \u00edndices, commodities, criptomoedas e ETFs na plataforma MetaTrader 5 da Axia.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1606\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1606\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c9 poss\u00edvel acessar a conta de negocia\u00e7\u00e3o MT5 a partir de diferentes computadores?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1606\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1606\"><p>Sim, voc\u00ea pode fazer login na sua conta de negocia\u00e7\u00e3o MT5 em diferentes computadores ao mesmo tempo. Isso tamb\u00e9m inclui o uso do aplicativo da plataforma MT4 no Android e no iOS.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1607\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1607\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Posso negociar no MT4 com uma conta MT5?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1607\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1607\"><p>Infelizmente, voc\u00ea n\u00e3o pode. Voc\u00ea precisa baixar e fazer login na mesma plataforma em que abriu inicialmente uma conta de negocia\u00e7\u00e3o.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1608\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1608\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Os EAs MT4 s\u00e3o compat\u00edveis com a plataforma MT5?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1608\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1608\"><p>N\u00e3o, os programas de negocia\u00e7\u00e3o automatizados na plataforma MetaTrader 4, conhecidos como Trading Expert, s\u00e3o codificados na linguagem MQL4. \u00c9 uma linguagem completamente diferente e n\u00e3o compat\u00edvel com a linguagem de programa\u00e7\u00e3o MQL5 utilizada na plataforma MetaTrader 5, apesar da grande semelhan\u00e7a no nome. Para automatizar a mesma estrat\u00e9gia de negocia\u00e7\u00e3o na plataforma MetaTrader 5, ela deve ser reprogramada do zero por um programador MQL5 profissional.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1609\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1609\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Como posso criar um extrato de conta na minha plataforma MT5?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1609\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1609\"><p>Para obter o relat\u00f3rio completo do seu hist\u00f3rico de negocia\u00e7\u00e3o MT5, clique na janela Hist\u00f3rico na lista de janelas exibida na parte inferior da plataforma. Dentro da janela Hist\u00f3rico, clique com o bot\u00e3o direito no relat\u00f3rio e clique em Relat\u00f3rio no menu. Por fim, voc\u00ea pode salvar o relat\u00f3rio do extrato da conta como um arquivo XML, que pode ser aberto no Excel. Alternativamente, voc\u00ea pode salv\u00e1-lo como um arquivo HTML, que pode ser aberto em um navegador da web.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-16010\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-16010\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Posso gerenciar m\u00faltiplas contas na plataforma MT5?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-16010\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-16010\"><p>Claro, voc\u00ea pode abrir e gerenciar diversas contas na plataforma MetaTrader 5, mas voc\u00ea tem acesso a uma conta de negocia\u00e7\u00e3o ao mesmo tempo na mesma plataforma de negocia\u00e7\u00e3o. As contas utilizadas s\u00e3o armazenadas e exibidas na janela do Navegador (CTL+N) onde voc\u00ea pode alternar entre elas, onde s\u00e3o categorizadas com base no seu tipo (contas reais ou demo) e no nome do servidor em que est\u00e3o abertas. Caso queira fazer login em mais de uma conta ao mesmo tempo, ser\u00e1 necess\u00e1rio instalar mais de uma plataforma em arquivos diferentes no seu computador.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"O que \\u00e9 a plataforma MetaTrader 5 (MT5)?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>MetaTrader 5 ou MT5 \\u00e9 uma plataforma de negocia\\u00e7\\u00e3o de m\\u00faltiplos ativos que permite negocia\\u00e7\\u00e3o de Forex, a\\u00e7\\u00f5es e futuros. Ele fornece ferramentas exemplares para an\\u00e1lise t\\u00e9cnica abrangente de movimentos de pre\\u00e7os, uso de negocia\\u00e7\\u00e3o automatizada usando algoritmos de software (bots de negocia\\u00e7\\u00e3o, consultores especializados) e servi\\u00e7os de negocia\\u00e7\\u00e3o de c\\u00f3pias.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Por que devo usar o MT5? \\u00c9 diferente da plataforma MetaTrader 4 (MT4)?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>A plataforma MetaTrader 5 foi lan\\u00e7ada em 2010, cinco anos ap\\u00f3s o lan\\u00e7amento do MetaTrader 4, que era, na altura, a plataforma mais utilizada entre traders novatos e corretoras para negocia\\u00e7\\u00e3o no mercado Forex atrav\\u00e9s de CFDs. A plataforma MetaTrader 5 conseguiu manter a caracter\\u00edstica mais importante, que \\u00e9 a facilidade de uso, al\\u00e9m de configurar um conjunto de recursos principais adicionais, especialmente gr\\u00e1ficos. Alguns dos recursos do MT5 incluem:<br \\\/>\\u2013 21 prazos localizados nos gr\\u00e1ficos em compara\\u00e7\\u00e3o com 9 prazos para MT4.<br \\\/>\\u2013 8 indicadores t\\u00e9cnicos adicionais.<br \\\/>\\u2013 Uso de MQL5 para programa\\u00e7\\u00e3o de negocia\\u00e7\\u00e3o automatizada (negocia\\u00e7\\u00e3o algor\\u00edtmica), que fornece mais ferramentas e execu\\u00e7\\u00e3o 20 vezes mais r\\u00e1pida que MQL4 para a plataforma MetaTrader 4.<br \\\/>\\u2013 Mais ordens de negocia\\u00e7\\u00e3o.<br \\\/>\\u2013 Negoceie um n\\u00famero infinitamente maior de ativos financeiros, enquanto a plataforma MT4 \\u00e9 projetada especificamente para negociar CFDs para um n\\u00famero limitado de pares forex.<br \\\/>\\u2013 Possibilidade de negocia\\u00e7\\u00e3o de a\\u00e7\\u00f5es reais em diversas bolsas de valores<br \\\/>\\u2013 Abertura de neg\\u00f3cios de hedge<br \\\/>\\u2013 Calend\\u00e1rio econ\\u00f4mico<br \\\/>Leia mais: Por que a plataforma de negocia\\u00e7\\u00e3o MetaTrader 5 \\u00e9 a melhor.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Como posso baixar e instalar a plataforma MT5?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Voc\\u00ea pode baixar e instalar a plataforma MetaTrader 5 do site Axia Trade aqui. Depois de instalar a plataforma, voc\\u00ea pode abrir uma conta de negocia\\u00e7\\u00e3o demo ou usar os dados de uma conta real para entrar na plataforma e come\\u00e7ar a negociar.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"O MT5 \\u00e9 adequado para iniciantes?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Sim, uma das caracter\\u00edsticas mais importantes da plataforma MetaTrader 5 \\u00e9 a extrema simplicidade da interface do usu\\u00e1rio. Permite a qualquer trader, independentemente da sua experi\\u00eancia no mercado, utiliz\\u00e1-lo quase diretamente, sem necessidade de especificar tempo e esfor\\u00e7o para aprender e habituar-se a ele. Tamb\\u00e9m possui um servi\\u00e7o de copy trades, que permite que traders novatos sigam e copiem traders profissionais de sucesso. A conhecida plataforma MetaTrader possui uma grande base de usu\\u00e1rios ativos e forma uma comunidade forte que fornece muitas respostas e solu\\u00e7\\u00f5es para todos os tipos de problemas que um trader iniciante pode encontrar.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quais ativos financeiros est\\u00e3o dispon\\u00edveis para negocia\\u00e7\\u00e3o na plataforma MT5?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Depende da corretora com a qual voc\\u00ea est\\u00e1 negociando, do tipo de ativos e dos mercados financeiros nos quais voc\\u00ea presta servi\\u00e7os de negocia\\u00e7\\u00e3o. Voc\\u00ea pode negociar todos os CFDs de pares de moedas (Forex), a\\u00e7\\u00f5es globais e \\u00e1rabes, \\u00edndices, commodities, criptomoedas e ETFs na plataforma MetaTrader 5 da Axia.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00c9 poss\\u00edvel acessar a conta de negocia\\u00e7\\u00e3o MT5 a partir de diferentes computadores?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Sim, voc\\u00ea pode fazer login na sua conta de negocia\\u00e7\\u00e3o MT5 em diferentes computadores ao mesmo tempo. Isso tamb\\u00e9m inclui o uso do aplicativo da plataforma MT4 no Android e no iOS.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Posso negociar no MT4 com uma conta MT5?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Infelizmente, voc\\u00ea n\\u00e3o pode. Voc\\u00ea precisa baixar e fazer login na mesma plataforma em que abriu inicialmente uma conta de negocia\\u00e7\\u00e3o.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Os EAs MT4 s\\u00e3o compat\\u00edveis com a plataforma MT5?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>N\\u00e3o, os programas de negocia\\u00e7\\u00e3o automatizados na plataforma MetaTrader 4, conhecidos como Trading Expert, s\\u00e3o codificados na linguagem MQL4. \\u00c9 uma linguagem completamente diferente e n\\u00e3o compat\\u00edvel com a linguagem de programa\\u00e7\\u00e3o MQL5 utilizada na plataforma MetaTrader 5, apesar da grande semelhan\\u00e7a no nome. Para automatizar a mesma estrat\\u00e9gia de negocia\\u00e7\\u00e3o na plataforma MetaTrader 5, ela deve ser reprogramada do zero por um programador MQL5 profissional.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Como posso criar um extrato de conta na minha plataforma MT5?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Para obter o relat\\u00f3rio completo do seu hist\\u00f3rico de negocia\\u00e7\\u00e3o MT5, clique na janela Hist\\u00f3rico na lista de janelas exibida na parte inferior da plataforma. Dentro da janela Hist\\u00f3rico, clique com o bot\\u00e3o direito no relat\\u00f3rio e clique em Relat\\u00f3rio no menu. Por fim, voc\\u00ea pode salvar o relat\\u00f3rio do extrato da conta como um arquivo XML, que pode ser aberto no Excel. Alternativamente, voc\\u00ea pode salv\\u00e1-lo como um arquivo HTML, que pode ser aberto em um navegador da web.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Posso gerenciar m\\u00faltiplas contas na plataforma MT5?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Claro, voc\\u00ea pode abrir e gerenciar diversas contas na plataforma MetaTrader 5, mas voc\\u00ea tem acesso a uma conta de negocia\\u00e7\\u00e3o ao mesmo tempo na mesma plataforma de negocia\\u00e7\\u00e3o. As contas utilizadas s\\u00e3o armazenadas e exibidas na janela do Navegador (CTL+N) onde voc\\u00ea pode alternar entre elas, onde s\\u00e3o categorizadas com base no seu tipo (contas reais ou demo) e no nome do servidor em que est\\u00e3o abertas. Caso queira fazer login em mais de uma conta ao mesmo tempo, ser\\u00e1 necess\\u00e1rio instalar mais de uma plataforma em arquivos diferentes no seu computador.<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe010af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe010af\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-468c8b9\" data-id=\"468c8b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be773e9 elementor-widget elementor-widget-AxiaSupportForm\" data-id=\"be773e9\" data-element_type=\"widget\" data-widget_type=\"AxiaSupportForm.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"slider-wrapper support-contact\">\n\t\t\t<div class=\"flex-column h-100 container js-contact-us\">\n\t\t\t\t<ul class=\"flex-row support-tabs js-tabs-links\">\n\t\t\t\t\t<li class=\"active\"><a class=\"js-tabs-link\" href=\"#contact-us\">Contate-nos<\/a><\/li>\n\t\t\t\t\t<li><a class=\"js-tabs-link\" href=\"#complaint\">Enviar uma reclama\u00e7\u00e3o<\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t<div class=\"support-contact-modal tab-active\" id=\"contact-us\">\n\t\t\t\t\t<div class=\"flex-column support-contact-modal-column\">\n\t\t\t\t\t\t<div class=\"flex-row\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"support-contact-img\" src=\"https:\/\/bcdn.axiainvestments.com\/wp-content\/uploads\/2023\/07\/man-1.png\" alt=\"\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"flex-row support-contact-heading\">\n\t\t\t\t\t\t\t<p>Contate-nos<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"flex-row support-contact-description\">\n\t\t\t\t\t\t\t<p>Estamos sempre ao seu servi\u00e7o.<br\/> Deixe seus dados e entraremos em contato<br\/> em breve<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"flex-column support-contact-modal-column\">\n\t\t\t\t\t\t<div class=\"support-form\">\n                            <div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-29866\"><form id=\"wpforms-form-29866\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"29866\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt-br\/wp-json\/wp\/v2\/pages\/5929?wpforms_form_id=29866\" data-token=\"d436487b7e84b206fdab6959bb297fa3\" data-token-time=\"1788371730\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-29866-field_3-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-rows\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29866-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><input type=\"text\" id=\"wpforms-29866-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"Seu nome completo*\" aria-errormessage=\"wpforms-29866-field_4-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29866-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"5\"><input type=\"tel\" id=\"wpforms-29866-field_5\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][5]\" placeholder=\"Telefone\" aria-errormessage=\"wpforms-29866-field_5-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29866-field_7-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"7\"><input type=\"email\" id=\"wpforms-29866-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" placeholder=\"Seu endere\u00e7o de e-mail*\" spellcheck=\"false\" aria-errormessage=\"wpforms-29866-field_7-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29866-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"16\"><input type=\"text\" id=\"wpforms-29866-field_16\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][16]\" placeholder=\"Assunto*\" aria-errormessage=\"wpforms-29866-field_16-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-29866-field_12-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"12\"><textarea id=\"wpforms-29866-field_12\" class=\"wpforms-field-medium\" name=\"wpforms[fields][12]\" placeholder=\"Mensagem\" aria-errormessage=\"wpforms-29866-field_12-error\" ><\/textarea><\/div><div id=\"wpforms-29866-field_14-container\" class=\"wpforms-field wpforms-field-checkbox contact-us-policy-checkbox\" data-field-id=\"14\"><fieldset><legend class=\"wpforms-field-label\"> <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-29866-field_14\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-29866-field_14_1\" name=\"wpforms[fields][14][]\" value=\"Ao enviar este formul\u00e1rio, voc\u00ea concorda com nossa &lt;a target=&quot;_blank&quot; href=&quot;https:\/\/docs.axiainvestments.com\/axia\/Axia_Privacy_Policy.pdf&quot; style=&quot;text-decoration: underline;&quot;&gt;Pol\u00edtica de Privacidade&lt;\/a&gt; *\" aria-errormessage=\"wpforms-29866-field_14_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29866-field_14_1\">Ao enviar este formul\u00e1rio, voc\u00ea concorda com nossa <a target=\"_blank\" href=\"https:\/\/docs.axiainvestments.com\/axia\/Axia_Privacy_Policy.pdf\" style=\"text-decoration: underline\">Pol\u00edtica de Privacidade<\/a> *<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-29866-field_13-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"13\"><input type=\"file\" id=\"wpforms-29866-field_13\" data-rule-extension=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\" data-rule-maxsize=\"52428800\" name=\"wpforms_29866_13\" accept=\".jpg,.jpeg,.jpe,.gif,.png,.bmp,.tiff,.tif,.webp,.avif,.ico,.heic,.heif,.heics,.heifs,.asf,.asx,.wmv,.wmx,.wm,.avi,.divx,.mov,.qt,.mpeg,.mpg,.mpe,.mp4,.m4v,.ogv,.webm,.mkv,.3gp,.3gpp,.3g2,.3gp2,.txt,.asc,.c,.cc,.h,.srt,.csv,.tsv,.ics,.rtx,.css,.vtt,.mp3,.m4a,.m4b,.aac,.ra,.ram,.wav,.ogg,.oga,.flac,.mid,.midi,.wma,.wax,.mka,.rtf,.pdf,.class,.tar,.zip,.gz,.gzip,.rar,.7z,.psd,.xcf,.doc,.pot,.pps,.ppt,.wri,.xla,.xls,.xlt,.xlw,.mpp,.docx,.docm,.dotx,.dotm,.xlsx,.xlsm,.xlsb,.xltx,.xltm,.xlam,.pptx,.pptm,.ppsx,.ppsm,.potx,.potm,.ppam,.sldx,.sldm,.onetoc,.onetoc2,.onepkg,.oxps,.xps,.odt,.odp,.ods,.odg,.odc,.odb,.odf,.wp,.wpd,.key,.numbers,.pages\" aria-errormessage=\"wpforms-29866-field_13-error\" ><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"29866\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/pages\/5929\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-29866\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar Mensagem\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar Mensagem<\/button><img decoding=\"async\" src=\"\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->                        <\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"complaint\" id=\"complaint\" dir=\"ltr\">\n\t\t\t\t\t<div class=\"complaint-top\">\n                        <div class=\"complaint__img\"><img decoding=\"async\" src=\"https:\/\/bcdn.axiainvestments.com\/wp-content\/uploads\/2023\/07\/man-2.png\" alt=\"axiaLogo\"><\/div>\n                        <div class=\"complaint-top-content\">\n                            <div class=\"complaint__heading\">\n                                <p>Enviar uma reclama\u00e7\u00e3o<\/p>\n                            <\/div>\n                            <div class=\"complaint__description\">\n\t\t                        Lamentamos saber que voc\u00ea teve uma experi\u00eancia desagrad\u00e1vel conosco. Forne\u00e7a-nos todos os detalhes necess\u00e1rios para que possamos investigar mais detalhadamente                            <\/div>\n                        <\/div>\n                    <\/div>\n                    <div class=\"complaint-subtitle\">\n\t                    As perguntas marcadas com um asterisco (*) s\u00e3o obrigat\u00f3rias.                    <\/div>\n\t\t\t\t\t<div class=\"complaint-form\">\n                        <div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-29872\"><form id=\"wpforms-form-29872\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"29872\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/pt-br\/wp-json\/wp\/v2\/pages\/5929\" data-token=\"58c4573b1b069c50073039e5dbab5e83\" data-token-time=\"1788371730\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#ffffff\" data-scroll=\"1\" role=\"progressbar\" aria-valuenow=\"1\" aria-valuemin=\"1\" aria-valuemax=\"4\" tabindex=\"-1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 4<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:25%;background-color:#ffffff\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-29872-field_9-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"9\"><\/div><div id=\"wpforms-29872-field_3-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-rows\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-29872-field_1-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_1\">T\u00edtulo<\/label><select id=\"wpforms-29872-field_1\" class=\"wpforms-field-medium choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][1]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Senhor<\/option><option value=\"Senhor\" >Senhor<\/option><option value=\"Senhora\" >Senhora<\/option><option value=\"Senhorita\" >Senhorita<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-29872-field_2-container\" class=\"wpforms-field wpforms-field-name text-only\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_2\">Nome completo <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-29872-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Nome completo\" aria-errormessage=\"wpforms-29872-field_2-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-29872-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_4\">N\u00famero do passaporte <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-29872-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"N\u00famero de identifica\u00e7\u00e3o ou passaporte\" aria-errormessage=\"wpforms-29872-field_4-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-29872-field_5-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-rows\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_6-container\" class=\"wpforms-field wpforms-field-text text-only\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_6\">Nacionalidade <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-29872-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" placeholder=\"Nacionalidade\" aria-errormessage=\"wpforms-29872-field_6-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_7-container\" class=\"wpforms-field wpforms-field-phone numbers-only\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_7\">Telefone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-29872-field_7\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-29872-field_7-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-29872-field_8-container\" class=\"wpforms-field wpforms-field-pagebreak next-btn\" data-field-id=\"8\"><div class=\"wpforms-clear wpforms-pagebreak-right\"><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"1\" data-formid=\"29872\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Pr\u00f3ximo<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  next-btn\" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-29872-field_11-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"11\"><label class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-rows\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_12-container\" class=\"wpforms-field wpforms-field-phone numbers-only\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_12\">N\u00famero de telefone residencial\/trabalho<\/label><input type=\"tel\" id=\"wpforms-29872-field_12\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][12]\" placeholder=\"N\u00famero de telefone residencial\/trabalho\" aria-errormessage=\"wpforms-29872-field_12-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_13-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_13\">Endere\u00e7o de e-mail Address: Endere\u00e7o <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-29872-field_13\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][13]\" placeholder=\"Endere\u00e7o de e-mail Address: Endere\u00e7o\" spellcheck=\"false\" aria-errormessage=\"wpforms-29872-field_13-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-29872-field_14-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"14\"><label class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-rows\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_15-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_15\">Endere\u00e7o<\/label><input type=\"text\" id=\"wpforms-29872-field_15\" class=\"wpforms-field-medium\" name=\"wpforms[fields][15]\" placeholder=\"Endere\u00e7o\" aria-errormessage=\"wpforms-29872-field_15-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_16-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_16\">Cidade<\/label><input type=\"text\" id=\"wpforms-29872-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" placeholder=\"Cidade\" aria-errormessage=\"wpforms-29872-field_16-error\" ><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-29872-field_17-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"17\"><div class=\"wpforms-clear wpforms-pagebreak-right\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"2\" data-formid=\"29872\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Anterior<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"2\" data-formid=\"29872\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Pr\u00f3ximo<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3  \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-29872-field_18-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"18\"><label class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Layout<\/label><div class=\"wpforms-field-layout-rows\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_19-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_19\">N\u00famero de usu\u00e1rio\/conta da conta mantida com a empresa (Axia Investments) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-29872-field_19\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][19]\" placeholder=\"N\u00famero de usu\u00e1rio\/conta da conta mantida com a empresa (Axia Investments)\" aria-errormessage=\"wpforms-29872-field_19-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-29872-field_20-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_20\">Quando ocorreu o problema?<\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29872-field_20\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][20][date]\" placeholder=\"Quando ocorreu o problema?\" aria-errormessage=\"wpforms-29872-field_20-error\" ><a title=\"Clear Date\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-29872-field_22-container\" class=\"wpforms-field wpforms-field-date-time date-picker-2\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_22\">Quando voc\u00ea notou pela primeira vez que poderia haver um problema? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-29872-field_22\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][22][date]\" placeholder=\"Quando voc\u00ea notou pela primeira vez que poderia haver um problema?\" aria-errormessage=\"wpforms-29872-field_22-error\" required><a title=\"Clear Date\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-29872-field_23-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"23\"><fieldset><legend class=\"wpforms-field-label\">Voc\u00ea comunicou sua reclama\u00e7\u00e3o \u00e0 Smarttool Trading SC Ltd. e\/ou seus associados? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-29872-field_23\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-29872-field_23_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][23][]\" value=\"Sim\" aria-errormessage=\"wpforms-29872-field_23_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29872-field_23_1\">Sim<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-29872-field_23_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][23][]\" value=\"N\u00e3o\" aria-errormessage=\"wpforms-29872-field_23_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29872-field_23_2\">N\u00e3o<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-29872-field_24-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"24\"><div class=\"wpforms-clear wpforms-pagebreak-right\"><button class=\"wpforms-page-button wpforms-page-prev wpforms-disabled\"\n\t\t\t\t\tdata-action=\"prev\" data-page=\"3\" data-formid=\"29872\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Anterior<\/button><button class=\"wpforms-page-button wpforms-page-next wpforms-disabled\"\n\t\t\t\t\tdata-action=\"next\" data-page=\"3\" data-formid=\"29872\" aria-disabled=\"true\" aria-describedby=\"wpforms-error-noscript\">Pr\u00f3ximo<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-4 last \" data-page=\"4\" style=\"display:none;\"><div id=\"wpforms-29872-field_25-container\" class=\"wpforms-field wpforms-field-text text-only\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_25\">Nome do representante da Smarttool Trading SC Ltd.<\/label><input type=\"text\" id=\"wpforms-29872-field_25\" class=\"wpforms-field-medium\" name=\"wpforms[fields][25]\" placeholder=\"Nome do representante da Smarttool Trading SC Ltd.\" aria-errormessage=\"wpforms-29872-field_25-error\" ><\/div><div id=\"wpforms-29872-field_38-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"38\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_38\">Por favor, insira o e-mail do representante da Smarttool Trading SC Ltd.<\/label><input type=\"email\" id=\"wpforms-29872-field_38\" class=\"wpforms-field-medium\" name=\"wpforms[fields][38]\" placeholder=\"Por favor, insira o e-mail do representante da Smarttool Trading SC Ltd.\" spellcheck=\"false\" aria-errormessage=\"wpforms-29872-field_38-error\" ><\/div><div id=\"wpforms-29872-field_27-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"27\"><fieldset><legend class=\"wpforms-field-label\">Voc\u00ea informou sua reclama\u00e7\u00e3o a alguma autoridade? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-29872-field_27\" class=\"wpforms-field-required\" data-choice-limit=\"1\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-29872-field_27_1\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"Sim\" aria-errormessage=\"wpforms-29872-field_27_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29872-field_27_1\">Sim<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-29872-field_27_2\" data-rule-check-limit=\"true\" name=\"wpforms[fields][27][]\" value=\"N\u00e3o\" aria-errormessage=\"wpforms-29872-field_27_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29872-field_27_2\">N\u00e3o<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-29872-field_28-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_28\">Qual autoridade financeira?<\/label><input type=\"text\" id=\"wpforms-29872-field_28\" class=\"wpforms-field-medium\" name=\"wpforms[fields][28]\" placeholder=\"Qual autoridade financeira?\" aria-errormessage=\"wpforms-29872-field_28-error\" ><\/div><div id=\"wpforms-29872-field_29-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"29\"><fieldset><legend class=\"wpforms-field-label\">Eu certifico e confirmo que, ao meu conhecimento, as informa\u00e7\u00f5es fornecidas acima s\u00e3o verdadeiras, precisas, corretas e completas. <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-29872-field_29\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-29872-field_29_1\" name=\"wpforms[fields][29][]\" value=\"Confirmo *\" aria-errormessage=\"wpforms-29872-field_29_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29872-field_29_1\">Confirmo *<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-29872-field_30-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"30\"><fieldset><legend class=\"wpforms-field-label\">Reconhe\u00e7o que a Smarttool Trading SC Ltd. fornecer\u00e1 a devida notifica\u00e7\u00e3o sobre a sua reclama\u00e7\u00e3o dentro de cinco (5) dias a partir do recebimento da mesma e lhe fornecer\u00e1 um n\u00famero de refer\u00eancia \u00fanico. Esse n\u00famero de refer\u00eancia \u00fanico dever\u00e1 ser utilizado em todos os seus contatos futuros com a Empresa, o Provedor Financeiro e\/ou a FSA em rela\u00e7\u00e3o \u00e0 reclama\u00e7\u00e3o espec\u00edfica. Envidaremos todos os esfor\u00e7os para investigar a sua reclama\u00e7\u00e3o e fornecer o resultado da nossa investiga\u00e7\u00e3o dentro de dois (2) meses a partir de hoje. Caso sejam necess\u00e1rias informa\u00e7\u00f5es adicionais, um de nossos representantes entrar\u00e1 em contato com voc\u00ea. Observe que, para agilizar a investiga\u00e7\u00e3o, solicitamos a sua total coopera\u00e7\u00e3o. Consulte a p\u00e1gina \u201cProcedimentos de Reclama\u00e7\u00f5es para Clientes\u201d para obter mais detalhes sobre o assunto. <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-29872-field_30\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-29872-field_30_1\" name=\"wpforms[fields][30][]\" value=\"Confirmo *\" aria-errormessage=\"wpforms-29872-field_30_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-29872-field_30_1\">Confirmo *<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-29872-field_36-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"36\"><label class=\"wpforms-field-label\" for=\"wpforms-29872-field_36\">Resumo <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-29872-field_36\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][36]\" aria-errormessage=\"wpforms-29872-field_36-error\" required><\/textarea><\/div><div id=\"wpforms-29872-field_10-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"10\"><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"29872\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/pages\/5929\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-29872\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->                    <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Centro de apoio Axia Estamos sempre aqui a seu servi\u00e7o. Para sua conveni\u00eancia, pesquise na nossa base de dados para obter respostas r\u00e1pidas sobre qualquer assunto Como fa\u00e7o para aprovisionar a minha conta? Disponibilizamos uma ampla variedade de formas de aprovisionar a sua conta, incluindo cart\u00e3o de cr\u00e9dito\/d\u00e9bito, transfer\u00eancia banc\u00e1ria e uma variedade de m\u00e9todos <a class=\"read-more\" href=\"https:\/\/axiainvestments.com\/pt-br\/support-center\/\">[read more]<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-5929","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/pages\/5929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/comments?post=5929"}],"version-history":[{"count":3,"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/pages\/5929\/revisions"}],"predecessor-version":[{"id":29956,"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/pages\/5929\/revisions\/29956"}],"wp:attachment":[{"href":"https:\/\/axiainvestments.com\/pt-br\/wp-json\/wp\/v2\/media?parent=5929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}